{"id":503,"count":0,"description":"Cellophane Roll Carrier manufactured by IMCOVEL. Valid for counter and 1,2 or 3 bodies options. Very durable.","link":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/","name":"Cellophane Roll Carrier","slug":"polypropilene-roll-carrier","taxonomy":"product_cat","parent":501,"meta":[],"menu_order":20,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cellophane Roll Carrier - Imcovel Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cellophane Roll Carrier - Imcovel Group\" \/>\n<meta property=\"og:description\" content=\"Cellophane Roll Carrier manufactured by IMCOVEL. Valid for counter and 1,2 or 3 bodies options. Very durable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/\" \/>\n<meta property=\"og:site_name\" content=\"Imcovel Group\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imcovel.com\/wp-content\/uploads\/2026\/03\/fabricante-bolsas-de-papel-imcovel.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/en\\\/product-categori\\\/roll-carriers\\\/polypropilene-roll-carrier\\\/\",\"url\":\"https:\\\/\\\/imcovel.com\\\/en\\\/product-categori\\\/roll-carriers\\\/polypropilene-roll-carrier\\\/\",\"name\":\"Cellophane Roll Carrier - Imcovel Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/en\\\/product-categori\\\/roll-carriers\\\/polypropilene-roll-carrier\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/en\\\/product-categori\\\/roll-carriers\\\/polypropilene-roll-carrier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/imcovel.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roll Carriers\",\"item\":\"https:\\\/\\\/imcovel.com\\\/en\\\/product-categori\\\/roll-carriers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cellophane Roll Carrier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/#website\",\"url\":\"https:\\\/\\\/imcovel.com\\\/\",\"name\":\"Imcovel Group\",\"description\":\"Fabrica de Papel\",\"publisher\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imcovel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/#organization\",\"name\":\"Imcovel Group\",\"alternateName\":\"Imcovel Group\",\"url\":\"https:\\\/\\\/imcovel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imcovel.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/40_ANIV_Imcovel-Group_Esp.png\",\"contentUrl\":\"https:\\\/\\\/imcovel.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/40_ANIV_Imcovel-Group_Esp.png\",\"width\":1056,\"height\":753,\"caption\":\"Imcovel Group\"},\"image\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/imcovelgroup\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/imcovel\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cellophane Roll Carrier - Imcovel Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/","og_locale":"en_US","og_type":"article","og_title":"Cellophane Roll Carrier - Imcovel Group","og_description":"Cellophane Roll Carrier manufactured by IMCOVEL. Valid for counter and 1,2 or 3 bodies options. Very durable.","og_url":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/","og_site_name":"Imcovel Group","og_image":[{"width":1920,"height":720,"url":"https:\/\/imcovel.com\/wp-content\/uploads\/2026\/03\/fabricante-bolsas-de-papel-imcovel.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/","url":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/","name":"Cellophane Roll Carrier - Imcovel Group","isPartOf":{"@id":"https:\/\/imcovel.com\/#website"},"breadcrumb":{"@id":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/polypropilene-roll-carrier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/imcovel.com\/en\/"},{"@type":"ListItem","position":2,"name":"Roll Carriers","item":"https:\/\/imcovel.com\/en\/product-categori\/roll-carriers\/"},{"@type":"ListItem","position":3,"name":"Cellophane Roll Carrier"}]},{"@type":"WebSite","@id":"https:\/\/imcovel.com\/#website","url":"https:\/\/imcovel.com\/","name":"Imcovel Group","description":"Fabrica de Papel","publisher":{"@id":"https:\/\/imcovel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imcovel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/imcovel.com\/#organization","name":"Imcovel Group","alternateName":"Imcovel Group","url":"https:\/\/imcovel.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/imcovel.com\/#\/schema\/logo\/image\/","url":"https:\/\/imcovel.com\/wp-content\/uploads\/2025\/11\/40_ANIV_Imcovel-Group_Esp.png","contentUrl":"https:\/\/imcovel.com\/wp-content\/uploads\/2025\/11\/40_ANIV_Imcovel-Group_Esp.png","width":1056,"height":753,"caption":"Imcovel Group"},"image":{"@id":"https:\/\/imcovel.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/imcovelgroup\/","https:\/\/www.linkedin.com\/company\/imcovel\/"]}]}},"_links":{"self":[{"href":"https:\/\/imcovel.com\/en\/wp-json\/wp\/v2\/product_cat\/503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imcovel.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/imcovel.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/imcovel.com\/en\/wp-json\/wp\/v2\/product_cat\/501"}],"wp:post_type":[{"href":"https:\/\/imcovel.com\/en\/wp-json\/wp\/v2\/product?product_cat=503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}