{"id":490,"count":2,"description":"Neutros","link":"https:\/\/imcovel.com\/fr\/categorie-produit\/bobines-rames-feuilles-papier-commerce-alimentation\/papier-cadeau-en-bobines-feuilles\/petits-rouleaux-papier-cadeaux\/neutros-fr\/","name":"Neutros","slug":"neutros-fr","taxonomy":"product_cat","parent":451,"meta":[],"menu_order":51,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neutros - Imcovel Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neutros - Imcovel Group\" \/>\n<meta property=\"og:description\" content=\"Neutros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/\" \/>\n<meta property=\"og:site_name\" content=\"Imcovel Group\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imcovel.com\/wp-content\/uploads\/2026\/03\/fabricante-bolsas-de-papel-imcovel.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/categoria-producto\\\/papel\\\/regalo-papel\\\/rollitos-papel-regalo\\\/neutros\\\/\",\"url\":\"https:\\\/\\\/imcovel.com\\\/categoria-producto\\\/papel\\\/regalo-papel\\\/rollitos-papel-regalo\\\/neutros\\\/\",\"name\":\"Neutros - Imcovel Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/categoria-producto\\\/papel\\\/regalo-papel\\\/rollitos-papel-regalo\\\/neutros\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/categoria-producto\\\/papel\\\/regalo-papel\\\/rollitos-papel-regalo\\\/neutros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/imcovel.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papel\",\"item\":\"https:\\\/\\\/imcovel.com\\\/categoria-producto\\\/papel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papel de Regalo\",\"item\":\"https:\\\/\\\/imcovel.com\\\/categoria-producto\\\/papel\\\/regalo-papel\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Rollitos\",\"item\":\"https:\\\/\\\/imcovel.com\\\/categoria-producto\\\/papel\\\/regalo-papel\\\/rollitos-papel-regalo\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Neutros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/#website\",\"url\":\"https:\\\/\\\/imcovel.com\\\/\",\"name\":\"Imcovel Group\",\"description\":\"Fabricantes de bolsas de papel y packaging personalizado\",\"publisher\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imcovel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/#organization\",\"name\":\"Imcovel Group\",\"alternateName\":\"Imcovel Group\",\"url\":\"https:\\\/\\\/imcovel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/imcovel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imcovel.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/40_ANIV_Imcovel-Group_Esp.png\",\"contentUrl\":\"https:\\\/\\\/imcovel.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/40_ANIV_Imcovel-Group_Esp.png\",\"width\":1056,\"height\":753,\"caption\":\"Imcovel Group\"},\"image\":{\"@id\":\"https:\\\/\\\/imcovel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/imcovelgroup\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/imcovel\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neutros - Imcovel Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/","og_locale":"fr_FR","og_type":"article","og_title":"Neutros - Imcovel Group","og_description":"Neutros","og_url":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/","og_site_name":"Imcovel Group","og_image":[{"width":1920,"height":720,"url":"https:\/\/imcovel.com\/wp-content\/uploads\/2026\/03\/fabricante-bolsas-de-papel-imcovel.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/","url":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/","name":"Neutros - Imcovel Group","isPartOf":{"@id":"https:\/\/imcovel.com\/#website"},"breadcrumb":{"@id":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/neutros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/imcovel.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Papel","item":"https:\/\/imcovel.com\/categoria-producto\/papel\/"},{"@type":"ListItem","position":3,"name":"Papel de Regalo","item":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/"},{"@type":"ListItem","position":4,"name":"Rollitos","item":"https:\/\/imcovel.com\/categoria-producto\/papel\/regalo-papel\/rollitos-papel-regalo\/"},{"@type":"ListItem","position":5,"name":"Neutros"}]},{"@type":"WebSite","@id":"https:\/\/imcovel.com\/#website","url":"https:\/\/imcovel.com\/","name":"Imcovel Group","description":"Fabricantes de bolsas de papel y packaging personalizado","publisher":{"@id":"https:\/\/imcovel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imcovel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/imcovel.com\/#organization","name":"Imcovel Group","alternateName":"Imcovel Group","url":"https:\/\/imcovel.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/imcovel.com\/#\/schema\/logo\/image\/","url":"https:\/\/imcovel.com\/wp-content\/uploads\/2025\/11\/40_ANIV_Imcovel-Group_Esp.png","contentUrl":"https:\/\/imcovel.com\/wp-content\/uploads\/2025\/11\/40_ANIV_Imcovel-Group_Esp.png","width":1056,"height":753,"caption":"Imcovel Group"},"image":{"@id":"https:\/\/imcovel.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/imcovelgroup\/","https:\/\/www.linkedin.com\/company\/imcovel\/"]}]}},"_links":{"self":[{"href":"https:\/\/imcovel.com\/fr\/wp-json\/wp\/v2\/product_cat\/490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imcovel.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/imcovel.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/imcovel.com\/fr\/wp-json\/wp\/v2\/product_cat\/451"}],"wp:post_type":[{"href":"https:\/\/imcovel.com\/fr\/wp-json\/wp\/v2\/product?product_cat=490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}